{"id":3260,"date":"2018-07-05T10:00:18","date_gmt":"2018-07-05T10:00:18","guid":{"rendered":"https:\/\/blog.12min.com\/br\/?p=3260"},"modified":"2019-04-13T22:46:21","modified_gmt":"2019-04-14T01:46:21","slug":"como-ser-educado","status":"publish","type":"post","link":"https:\/\/blog.12min.com\/br\/como-ser-educado\/","title":{"rendered":"Como ser educado com todos e em todo lugar"},"content":{"rendered":"<p class=\"wpwc-reading-time\">7 min de leitura \u231a&nbsp;<\/p><div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/3260?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><\/a><a href=\"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/3260?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><\/a><\/div><p><span style=\"font-weight: 400\">Voc\u00ea se lembra daquelas tr\u00eas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia &#8211; \u201cObrigado(a)\u201d, por \u201cfavor\u201d, \u201cdesculpe\u201d? Pois \u00e9, elas continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3263\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_260891789-300x200.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"400\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_260891789-300x200.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_260891789-768x512.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_260891789.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Mas cuidado, porque n\u00f3s n\u00e3o nos comunicamos apenas com as palavras. O <\/span><span style=\"font-weight: 400\">nosso corpo fala<\/span><span style=\"font-weight: 400\">. Nossos gestos, comportamentos e at\u00e9 o tom de voz emitem mensagens valios\u00edssimas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por exemplo, dependendo do seu tom de voz ou da sua express\u00e3o facial, um simples \u201cmuito obrigado\u201d pode parecer arrog\u00e2ncia ou at\u00e9 mesmo cinismo. Ou seja, o nosso corpo pode contradizer as nossas palavras.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Diploma e educa\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400\">N\u00e3o confunda anos de estudo com ter educa\u00e7\u00e3o. Uma pessoa pode carregar um diploma de Phd da conceituada universidade americana de Harvard e ser um grande mal-educado, desrespeitando os outros ou se comportando de maneira inadequada em locais p\u00fablicos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por outro lado, existem v\u00e1rias pessoas que sequer sabem escrever o pr\u00f3prio nome corretamente, nunca foram \u00e0 escola, no entanto, s\u00e3o um \u201cpo\u00e7o\u201d de educa\u00e7\u00e3o. Tratam a todos com simpatia, humildade e respeito.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Aprendendo sempre<\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3265\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_175635185-300x207.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"414\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_175635185-300x207.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_175635185-768x530.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_175635185.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"font-weight: 400\">A gente costuma dizer que educa\u00e7\u00e3o vem do ber\u00e7o. \u00c9 verdade. Mas n\u00f3s n\u00e3o precisamos parar a\u00ed. \u00c9 poss\u00edvel aprender cada dia mais sobre como ser educado. A leitura \u00e9 um excelente caminho a seguir.<\/span><\/p>\n<p><a href=\"http:\/\/blog.12min.com.br\/encontrar-bons-livros-para-ler\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">\u00c9 muito f\u00e1cil encontrar bons livros<\/span><\/a><span style=\"font-weight: 400\"> que nos ajudam a evoluir, inclusive, no relacionamento com as pessoas. Podemos desenvolver at\u00e9 mesmo algumas t\u00e9cnicas de etiqueta, com dicas muito espec\u00edficas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Essas dicas podem ser sobre os <\/span><a href=\"https:\/\/revistacrescer.globo.com\/Gravidez\/Pos-parto\/noticia\/2015\/03\/visita-ao-recem-nascido-15-dicas-de-etiqueta.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">cuidados ao visitar um rec\u00e9m-nascido<\/span><\/a><span style=\"font-weight: 400\">, as boas maneiras em um casamento, como dar e receber presentes&#8230; e muito mais.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Como ser educado sempre?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Voc\u00ea domina as tr\u00eas palavrinhas m\u00e1gicas e algumas outras express\u00f5es como \u201ccom licen\u00e7a\u201d, \u201cboa noite\u201d, \u201cbem-vindo\u201d etc. E voc\u00ea, tamb\u00e9m, entende sobre linguagem corporal.<\/span><\/p>\n<p><span style=\"font-weight: 400\">No entanto, todo esse conhecimento s\u00f3 far\u00e1 de voc\u00ea uma pessoa educada, se ele for usado corretamente, a todo momento, com todos ao seu redor.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ser uma raridade de pessoa com o seu chefe e seus colegas pr\u00f3ximos, por\u00e9m, passar por cima zelador do pr\u00e9dio como um trator, n\u00e3o faz de voc\u00ea uma pessoa educada.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nesse caso espec\u00edfico, o pessoal da empresa pode achar que voc\u00ea \u00e9 um <\/span><a href=\"https:\/\/blog.12min.com\/br\/relacoes-interpessoais-no-trabalho\/\"><span style=\"font-weight: 400\">puxa-saco<\/span><\/a><span style=\"font-weight: 400\">. Uma imagem bem diferente de quem quer ser visto como um bem-educado.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Como ser educado em 6 situa\u00e7\u00f5es diferentes<\/span><\/h2>\n<h3><b> 1.<\/b><b>\u00a0 Como ser educado n<\/b><b>o cotidiano<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3266\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_141076960-300x201.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"401\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_141076960-300x201.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_141076960-768x514.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_141076960.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Use e abuse das palavrinhas m\u00e1gicas.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Sempre cumprimente as pessoas com um bom dia, boa tarde, boa noite\u2026 Um sorriso sincero n\u00e3o faz mal a ningu\u00e9m e \u00e9 de gra\u00e7a.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Fale baixo, evite gesticular em excesso.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Agrade\u00e7a um favor e elogie com sinceridade, sempre que for conveniente.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Seja prestativo. Que tal ajudar um velhinho a atravessar a rua ou carregar uma sacola de supermercado para a senhora gr\u00e1vida.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Segure a porta e a mantenha aberta para a pessoa que vem logo atr\u00e1s. Isso inclui os elevadores.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Redobre a paci\u00eancia com os mais velhos.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">N\u00e3o comente e n\u00e3o fa\u00e7a julgamentos sobre a vida particular do vizinho, do colega de trabalho ou de qualquer outra pessoa.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">N\u00e3o fure a fila do banco, nem do cinema, do \u00f4nibus\u2026<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">N\u00e3o descarregue sua raiva no caixa do supermercado. Ele n\u00e3o tem culpa se os pre\u00e7os subiram, o produto est\u00e1 estragado ou em falta. Se quer reclamar, procure o gerente.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nunca, nunca, nunca coloque o dedo no nariz. Comer a melequinha ent\u00e3o\u2026<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Se espirrar, proteja a boca com o antebra\u00e7o. Nada de usar as m\u00e3os e depois cumprimentar algu\u00e9m ou <\/span><a href=\"https:\/\/veja.abril.com.br\/saude\/um-unico-espirro-pode-contaminar-uma-sala-por-horas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">contaminar o ambiente inteiro<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Mantenha as ruas e as cal\u00e7adas limpas.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Nem pense em cuspir no ch\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Essa dica, agora, \u00e9 para os homens: sabe aquela mania de colocar a m\u00e3o dentro da cueca o tempo todo, ou mesmo ficar co\u00e7ando as partes \u00edntimas sobre as cal\u00e7as. Esque\u00e7a isso.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">E um recado para as mulheres: nada de ficar ajeitando as al\u00e7as do suti\u00e3 em p\u00fablico.<\/span><\/li>\n<\/ul>\n<h3><b>2.<\/b> <b>Como ser educado d<\/b><b>urante as refei\u00e7\u00f5es<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3271\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado-300x200.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Coma com a boca fechada.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Mastigue devagar e sem fazer barulhos. Ningu\u00e9m merece ru\u00eddos de gente comendo ao lado.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">N\u00e3o converse com a boca cheia de comida. Engula tudo antes de come\u00e7ar a falar.<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"http:\/\/revistadonna.clicrbs.com.br\/porai\/2015\/05\/06\/bons-modos-a-mesa-como-usar-garfo-e-faca-de-maneira-correta\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">Use os talheres corretamente<\/span><\/a><span style=\"font-weight: 400\">. \u00c0s vezes, \u00e9 permitido <\/span><a href=\"https:\/\/www.vix.com\/pt\/bdm\/familia\/comendo-com-as-maos\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">comer com as m\u00e3os <\/span><\/a><span style=\"font-weight: 400\">\u2013 procure se informar sobre o assunto.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Leve a comida at\u00e9 a boca e n\u00e3o o contr\u00e1rio.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Use guardanapos. N\u00e3o limpe a boca com as m\u00e3os.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">S\u00f3 comece a comer depois que todos estiverem servidos.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Em um restaurante, n\u00e3o \u201cmonopolize\u201d o gar\u00e7om.<\/span><\/li>\n<\/ul>\n<h3><b> 3.<\/b> <b>Como ser educado no\u00a0<\/b><b>contato com as pessoas<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3272\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_1086419282-300x206.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"412\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_1086419282-300x206.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_1086419282-768x527.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_1086419282.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">N\u00e3o coloque a m\u00e3o em outra pessoa sem permiss\u00e3o. Tem gente que odeia ser tocado. Nesse caso, ainda, existem quest\u00f5es culturais que devem ser observadas e respeitadas, inclusive, no ambiente de trabalho.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Nada de ficar ajeitando a gola da camisa do outro, tirando fio de cabelo da blusa etc. Somente fa\u00e7a isso com o consentimento pr\u00e9vio.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Com as crian\u00e7as, \u00e9 preciso permiss\u00e3o dos pais para toc\u00e1-las, peg\u00e1-las no colo ou abra\u00e7\u00e1-las. A n\u00e3o ser que seja algu\u00e9m muito pr\u00f3ximo de voc\u00ea.<\/span><\/li>\n<li>E por favor, controle aquele impulso de assanhar o cabelo do garotinho ou garotinha. Voc\u00ea vai ganhar um inimigo se n\u00e3o seguir essa dica.<\/li>\n<\/ul>\n<h3><b>4.<\/b> <b>Como ser educado d<\/b><b>urante uma conversa<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3268\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_671274400-300x200.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"401\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_671274400-300x200.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_671274400-768x513.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_671274400.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Mantenha contato visual com a pessoa com a qual estiver falando. Isso n\u00e3o significa encar\u00e1-la.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Controle a sua ansiedade e n\u00e3o interrompa uma pessoa, quando ela estiver falando. Espere a sua vez.<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o fique checando o <\/span><a href=\"https:\/\/tecnologia.uol.com.br\/noticias\/redacao\/2013\/07\/23\/especialista-da-dicas-de-etiqueta-para-usuarios-de-telefone-celular.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">celular<\/span><\/a><span style=\"font-weight: 400\"> a todo momento. Atenda uma chamada apenas em caso de emerg\u00eancia. Mesmo assim, explique que \u00e9 urgente.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Se estiver conversando com algu\u00e9m, jamais d\u00ea as costas e deixe a pessoa falando sozinha. Isso sim \u00e9 passar dos limites&#8230;<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o tente impor o seu ponto de vista. Respeite as opini\u00f5es dos outros.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Mantenha um tom de voz suave. Nem se a pessoa tiver dificuldade de audi\u00e7\u00e3o voc\u00ea deve gritar. Nesse caso, fique de frente para que ela possa observar os movimentos dos seus l\u00e1bios.<\/span><\/li>\n<\/ul>\n<h3><b>5.<\/b> <b>Como ser educado n<\/b><b>uma reuni\u00e3o de trabalho<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3267\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_137657909-300x199.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"398\" srcset=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_137657909-300x199.jpg 300w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_137657909-768x510.jpg 768w, https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_137657909.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Seja pontual.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Use roupas apropriadas.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Respeite a hierarquia.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Cumprimente a todos.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Esteja informado sobre o tema da reuni\u00e3o.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Tenha em m\u00e3os tudo o que voc\u00ea vai precisar para a reuni\u00e3o.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Procure se informar previamente sobre quem s\u00e3o as pessoas presentes e que setores (ou empresas) elas representam.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Mantenha uma postura correta.<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o se disperse rabiscando pap\u00e9is.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Evite conversas paralelas.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Mais uma vez, esque\u00e7a o celular. Mantenha-o desligado ou com o \u00e1udio desativado.<\/span><\/li>\n<\/ul>\n<h3><b>6.<\/b> <b>Como ser educado n<\/b><b>o tr\u00e2nsito<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3274\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado-2-300x197.jpg\" alt=\"Como ser educado\" width=\"600\" height=\"395\" \/><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Economize a buzina. Use-a somente se for extremamente necess\u00e1ria.<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o fique acelerando para apressar as pessoas na faixa de pedestre. Tenha paci\u00eancia.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Paci\u00eancia \u00e9 o que n\u00e3o pode faltar no tr\u00e2nsito. Em especial com motoristas idosos.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Respeite as sinaliza\u00e7\u00f5es e sempre d\u00ea prefer\u00eancia para os pedestres.<\/span><\/li>\n<li><span style=\"font-weight: 400\">Parou num engarrafamento? N\u00e3o adianta ficar buzinando, xingando ou gesticulando. O motorista \u00e0 sua frente quer sair dali t\u00e3o r\u00e1pido quanto voc\u00ea.<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o pare na faixa de pedestre e nem em locais proibidos. Al\u00e9m de ilegal, \u00e9 falta de respeito.<\/span><\/li>\n<li><span style=\"font-weight: 400\">N\u00e3o atire nada pelas janelas. Mantenha uma sacolinha no carro para colocar papel de bala, chicletes, casca de mexerica e outros lixinhos&#8230;<\/span><\/li>\n<\/ul>\n<h2><span style=\"font-weight: 400\">A linguagem corporal &#8211; onde est\u00e1 o perigo<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Voc\u00ea se lembra que mencionamos a import\u00e2ncia da comunica\u00e7\u00e3o n\u00e3o-verbal? Veja, agora, 6 linguagens do corpo para as quais voc\u00ea deve redobrar a sua aten\u00e7\u00e3o.<\/span><\/p>\n<ol>\n<li><b> Cruzar os bra\u00e7os: <\/b><span style=\"font-weight: 400\">indica desinteresse.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Algumas pessoas entendem, tamb\u00e9m, como uma postura defensiva ou inseguran\u00e7a. N\u00e3o fa\u00e7a isso quando estiver conversando com algum colega de trabalho e, principalmente, com o seu chefe.<\/span><\/p>\n<ol start=\"2\">\n<li><b> Evitar o contato visual<\/b><span style=\"font-weight: 400\">: transmite a sensa\u00e7\u00e3o de desonestidade.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Os especialistas recomendam olhar diretamente no olho do interlocutor por poucos segundos e depois desviar o olhar. Repita o movimento com frequ\u00eancia. \u00c9 s\u00f3 praticar. <\/span><\/p>\n<ol start=\"3\">\n<li><b> Dar as costas enquanto a pessoa ainda est\u00e1 falando<\/b><span style=\"font-weight: 400\">: demonstra falta de interesse.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Esse comportamento indica, tamb\u00e9m, uma total falta de respeito pela outra pessoa. Se voc\u00ea tem outro compromisso e precisa sair, explique a situa\u00e7\u00e3o para o seu ouvinte e pe\u00e7a desculpas, antes de se retirar.<\/span><\/p>\n<ol start=\"4\">\n<li><b> Bocejar v\u00e1rias vezes seguidas<\/b><span style=\"font-weight: 400\">: um jeito nada simp\u00e1tico de demonstrar cansa\u00e7o.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Ficar bocejando o tempo todo mostra, ainda, que voc\u00ea est\u00e1 entediado com a pessoa ou com o assunto em pauta. <\/span><\/p>\n<ol start=\"5\">\n<li><b> Apontar o dedo no rosto de algu\u00e9m<\/b><span style=\"font-weight: 400\">: ningu\u00e9m merece tanta grosseria.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Infelizmente, muitas pessoas fazem isso sem ter a consci\u00eancia do grau de agressividade. \u00c9 uma atitude que compromete a empatia.<\/span><\/p>\n<ol start=\"6\">\n<li><b> Manias e cacoetes<\/b><span style=\"font-weight: 400\">: transmitem inseguran\u00e7a ou desinteresse.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400\">Manias e cacoetes como roer as unhas, enrolar os cabelos ou os fios da barba, riscar ou picar pap\u00e9is durante uma reuni\u00e3o podem incomodar muito a pessoa ao lado.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Os ganhos<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Essas foram algumas dicas simples e legais de como ser educado em tempo integral e sobre os cuidados com a linguagem corporal. Lembre-se sempre que todas as pessoas querem ser tratados com considera\u00e7\u00e3o e respeito. TODAS.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Voc\u00ea s\u00f3 tem a ganhar sendo educado 24 horas por dia. Educa\u00e7\u00e3o facilita o r<\/span><a href=\"https:\/\/blog.12min.com\/br\/como-ser-mais-comunicativo-no-trabalho\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">elacionamento interpessoal<\/span><\/a><span style=\"font-weight: 400\"> e abre oportunidades.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m de uma pessoa educada, voc\u00ea pode ser tamb\u00e9m um expert em comportamento humano. Clique <\/span><a href=\"http:\/\/blog.12min.com.br\/livros-comportamento-humano\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">aqui<\/span><\/a><span style=\"font-weight: 400\"> para conhecer as cinco sugest\u00f5es de livros imperd\u00edveis sobre esse assunto.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">O valor dos livros<\/span><\/h2>\n<p><span style=\"font-weight: 400\">A leitura \u00e9 sempre uma boa escolha para as pessoas que buscam evoluir. A plataforma <\/span><a href=\"https:\/\/12min.com\/br\/\"><span style=\"font-weight: 400\">12MIN<\/span><\/a><span style=\"font-weight: 400\"> est\u00e1 repleta de t\u00edtulos e n\u00f3s selecionamos um que h\u00e1 anos vem transformando a vida de muita gente. Anote a\u00ed:<\/span><\/p>\n<h3><a href=\"https:\/\/12min.com\/br\/como-fazer-amigos-e-influenciar-pessoas\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400\">Como Fazer Amigos e Influenciar Pessoas<\/span><\/a><span style=\"font-weight: 400\"> &#8211; <\/span><span style=\"font-weight: 400\">Dale Carnegie<\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2881\" src=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/06\/como-ser-mais-comunicativo-pasted-image-0-197x300.png\" alt=\"Como ser educado\" width=\"120\" height=\"183\" \/><\/p>\n<p><span style=\"font-weight: 400\">Esse \u00e9 um cl\u00e1ssico que teve sua primeira publica\u00e7\u00e3o na d\u00e9cada de 40. Hoje, em sua 51\u00ba edi\u00e7\u00e3o, continua atual\u00edssimo. O livro \u00e9 dividido em princ\u00edpios, que s\u00e3o regrinhas simples para transformar voc\u00ea em uma pessoa mais admirada, capaz de influenciar os outros e fazer amigos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Voc\u00ea curtiu esse post? Deixe o seu coment\u00e1rio. E aproveite para compartilhar as informa\u00e7\u00f5es com os seus contatos. Quem sabe, aquele colega inconveniente n\u00e3o aprende um pouco mais sobre como ser educado?<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>7 min de leitura \u231a&nbsp;Voc\u00ea se lembra daquelas tr\u00eas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia &#8211; \u201cObrigado(a)\u201d, por \u201cfavor\u201d, \u201cdesculpe\u201d? Pois \u00e9, elas continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado. Mas cuidado, porque n\u00f3s n\u00e3o nos comunicamos apenas com as palavras. O nosso corpo [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":3262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conhecimento","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como ser educado com todos e em todo lugar - Blog do 12min<\/title>\n<meta name=\"description\" content=\"Aquelas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.12min.com\/br\/como-ser-educado\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como ser educado com todos e em todo lugar - Blog do 12min\" \/>\n<meta property=\"og:description\" content=\"Aquelas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.12min.com\/br\/como-ser-educado\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do 12min\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-05T10:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-14T01:46:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_130105307.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emir Zecovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emir Zecovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como ser educado com todos e em todo lugar - Blog do 12min","description":"Aquelas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.12min.com\/br\/como-ser-educado\/","og_locale":"en_US","og_type":"article","og_title":"Como ser educado com todos e em todo lugar - Blog do 12min","og_description":"Aquelas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.","og_url":"https:\/\/blog.12min.com\/br\/como-ser-educado\/","og_site_name":"Blog do 12min","article_published_time":"2018-07-05T10:00:18+00:00","article_modified_time":"2019-04-14T01:46:21+00:00","og_image":[{"width":1000,"height":801,"url":"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_130105307.jpg","type":"image\/jpeg"}],"author":"Emir Zecovic","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Emir Zecovic","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/","url":"https:\/\/blog.12min.com\/br\/como-ser-educado\/","name":"Como ser educado com todos e em todo lugar - Blog do 12min","isPartOf":{"@id":"https:\/\/blog.12min.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/#primaryimage"},"image":{"@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_130105307.jpg","datePublished":"2018-07-05T10:00:18+00:00","dateModified":"2019-04-14T01:46:21+00:00","author":{"@id":"https:\/\/blog.12min.com\/br\/#\/schema\/person\/ccaf1a7ac6cac4265aa3afb02ae667f4"},"description":"Aquelas palavrinhas m\u00e1gicas que todos n\u00f3s aprendemos na inf\u00e2ncia continuam na moda e s\u00e3o a base de todo manual de orienta\u00e7\u00e3o sobre como ser educado.","breadcrumb":{"@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.12min.com\/br\/como-ser-educado\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/#primaryimage","url":"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_130105307.jpg","contentUrl":"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2018\/07\/Como-ser-educado.-shutterstock_130105307.jpg","width":1000,"height":801,"caption":"Networking Profissional"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.12min.com\/br\/como-ser-educado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog.12min.com\/br\/"},{"@type":"ListItem","position":2,"name":"Como ser educado com todos e em todo lugar"}]},{"@type":"WebSite","@id":"https:\/\/blog.12min.com\/br\/#website","url":"https:\/\/blog.12min.com\/br\/","name":"Blog do 12min","description":"Livros, Audiobooks e Resumos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.12min.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.12min.com\/br\/#\/schema\/person\/ccaf1a7ac6cac4265aa3afb02ae667f4","name":"Emir Zecovic","description":"Emir is the Head of Marketing\u00a0at 12min. In his spare time, he loves to meditate and play soccer.","url":"https:\/\/blog.12min.com\/br\/author\/emir\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/3260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/comments?post=3260"}],"version-history":[{"count":5,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/3260\/revisions"}],"predecessor-version":[{"id":7197,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/3260\/revisions\/7197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/media\/3262"}],"wp:attachment":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/media?parent=3260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/categories?post=3260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/tags?post=3260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}