{"id":913,"date":"2017-09-18T21:33:02","date_gmt":"2017-09-18T21:33:02","guid":{"rendered":"http:\/\/blog.12min.com.br\/?p=913"},"modified":"2018-10-26T18:13:12","modified_gmt":"2018-10-26T18:13:12","slug":"marketing-de-conteudo","status":"publish","type":"post","link":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/","title":{"rendered":"Por que o Marketing de Conte\u00fado \u00e9 importante para qualquer neg\u00f3cio"},"content":{"rendered":"<p class=\"wpwc-reading-time\">6 min de leitura \u231a&nbsp;<\/p><div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/913?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><\/a><a href=\"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/913?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><\/a><\/div><p><span style=\"font-weight: 400\">Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo <\/span><a href=\"https:\/\/rockcontent.com\/blog\/marketing-de-conteudo\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Marketing de Conte\u00fado<\/span><\/a><span style=\"font-weight: 400\"> em algum lugar. Nos \u00faltimos anos, a estrat\u00e9gia vem ganhando cada vez mais reconhecimento e muitas empresas est\u00e3o investindo pesado no uso do <\/span><b>conte\u00fado de qualidade para atrair o seu p\u00fablico.<\/b><br \/>\n<span style=\"font-weight: 400\">Quase 92% das empresas entrevistadas pela pesquisa <\/span><a href=\"http:\/\/contenttrends.com.br\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Content Trends 2017 <\/span><\/a><span style=\"font-weight: 400\">j\u00e1 afirmam investir na estrat\u00e9gia. Al\u00e9m disso, cerca de 61% das empresas tamb\u00e9m pretendem aumentar o investimento em Marketing de Conte\u00fado no pr\u00f3ximo ano.<\/span><br \/>\n<span style=\"font-weight: 400\">Por que tantas empresas est\u00e3o apostando pesado no conte\u00fado? Vamos mostrar para voc\u00ea os principais motivos para se investir na estrat\u00e9gia. Pronto para descobrir porque o Marketing de Conte\u00fado \u00e9 importante para a estrat\u00e9gia de <\/span><a href=\"https:\/\/rockcontent.com\/blog\/marketing-digital\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">marketing digital<\/span><\/a><span style=\"font-weight: 400\"> de qualquer neg\u00f3cio?<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 1: Visibilidade nos mecanismos de busca<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Quando voc\u00ea tem uma d\u00favida sobre algo, o que voc\u00ea faz? Joga no Google.<\/span><br \/>\n<span style=\"font-weight: 400\">O mecanismo de busca \u00e9 o or\u00e1culo da internet: \u00e9 muito raro encontrar um usu\u00e1rio que n\u00e3o use o Google para sanar suas d\u00favidas sobre algum assunto. E \u00e9 a\u00ed que entra o Marketing de Conte\u00fado e a sua empresa! <\/span><br \/>\n<span style=\"font-weight: 400\">O maior princ\u00edpio da estrat\u00e9gia \u00e9 criar conte\u00fado de qualidade para <\/span><b>resolver um problema ou tirar uma d\u00favida da sua <\/b><a href=\"http:\/\/rockcontent.com\/blog\/personas\" target=\"_blank\" rel=\"noopener\"><b>persona<\/b><\/a>\u00a0(entenda melhor esse conceito no <a href=\"https:\/\/app.adjust.com\/7mvfth8?deeplink=twelvemin:\/\/book\/buyer-personas&amp;redirect_windows=https:\/\/12min.com\/br\/buyer-personas&amp;redirect_macos=https:\/\/12min.com\/br\/buyer-personas\" target=\"_blank\" rel=\"noopener\">livro de Adele Revella<\/a>)<span style=\"font-weight: 400\">, ou seja, do seu comprador ideal.<\/span><br \/>\n<span style=\"font-weight: 400\">Assim, voc\u00ea vai fazer uma pesquisa de <\/span><a href=\"https:\/\/rockcontent.com\/blog\/o-que-sao-palavras-chave\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">palavras-chave<\/span><\/a><span style=\"font-weight: 400\"> para descobrir o que a sua persona busca no Google, e logo depois voc\u00ea vai produzir um conte\u00fado perfeito para aquela palavra-chave. Otimize o seu post com t\u00e9cnicas de <\/span><a href=\"https:\/\/rockcontent.com\/blog\/o-que-e-seo\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">SEO<\/span><\/a><span style=\"font-weight: 400\"> (<\/span><i><span style=\"font-weight: 400\">Search Engine Optimization<\/span><\/i><span style=\"font-weight: 400\">, ou otimiza\u00e7\u00e3o para mecanismos de busca) e link building, divulgue-o bastante e acompanhe a performance daquele conte\u00fado no Google. Se ele for o melhor sobre o tema e estiver 100% otimizado, as chances da sua empresa parar <\/span><b>na primeira p\u00e1gina do buscador s\u00e3o enormes!<\/b><br \/>\n<span style=\"font-weight: 400\">Estando na primeira p\u00e1gina, quando o usu\u00e1rio buscar por aquela palavra-chave, ele provavelmente vai clicar no seu conte\u00fado. Se voc\u00ea tiver resolvido sua d\u00favida, ele vai passar a confiar na sua marca e voc\u00ea acabou de ganhar um leitor (e poss\u00edvel cliente futuro) fiel.<\/span><br \/>\n<span style=\"font-weight: 400\">O Marketing de Conte\u00fado funciona basicamente dessa maneira: produzindo conte\u00fado de qualidade, com estrat\u00e9gias de SEO, para melhorar a visibilidade da sua empresa na internet. Afinal, quem n\u00e3o quer estar na primeira p\u00e1gina do Google?<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 2: O Marketing de Conte\u00fado proporciona mais conte\u00fado de marca<\/span><\/h3>\n<p><span style=\"font-weight: 400\">O motivo n\u00famero 2 parece \u00f3bvio quando estamos falando de uma estrat\u00e9gia que se baseia principalmente na produ\u00e7\u00e3o de conte\u00fado, mas vamos explic\u00e1-lo um pouco melhor. Quando voc\u00ea investe no Marketing de Conte\u00fado, \u00e9 essencial que voc\u00ea crie uma frequ\u00eancia de postagem no seu blog. O n\u00famero ideal varia de empresa para empresa, \u00e9 claro, mas pense em postar pelo menos 2 ou 3 vezes por semana.<\/span><br \/>\n<span style=\"font-weight: 400\">Vamos supor que voc\u00ea escolha postar 3 vezes por semana no <\/span><a href=\"https:\/\/rockcontent.com\/blog\/como-criar-um-blog\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">blog<\/span><\/a><span style=\"font-weight: 400\"> da sua empresa. No final do m\u00eas, voc\u00ea ter\u00e1 produzido cerca de 12 conte\u00fados. S\u00e3o 12 conte\u00fados onde voc\u00ea est\u00e1 tirando d\u00favidas do seu comprador ideal, explicando conceitos ou ajudando-o em algum problema que ele tinha. Esse volume de conte\u00fado de qualidade \u00e9 muito relevante! <\/span><br \/>\n<span style=\"font-weight: 400\">Quanto mais bom conte\u00fado voc\u00ea publica no seu blog, <\/span><b>mais a sua marca estar\u00e1 exposta na internet.<\/b><span style=\"font-weight: 400\"> Mais exposi\u00e7\u00e3o gera mais oportunidades de neg\u00f3cios, que gera mais clientes.. e por a\u00ed vai!<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 3: Com o Marketing de Conte\u00fado voc\u00ea ganha mais relev\u00e2ncia nas redes sociais<\/span><\/h3>\n<p><span style=\"font-weight: 400\">A maioria das empresas sofre bastante na hora de produzir conte\u00fado para as <\/span><a href=\"https:\/\/rockcontent.com\/blog\/marketing-nas-redes-sociais\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">redes sociais<\/span><\/a><span style=\"font-weight: 400\">.<\/span><br \/>\n<span style=\"font-weight: 400\">Muitas n\u00e3o sabem quais assuntos abordar, como abordar, e acabam abandonando seus canais por n\u00e3o ver resultado nas redes sociais. Esse \u00e9 um grande erro! As redes sociais, hoje, funcionam como uma vitrine na internet. <\/span><b>Elas amplificam a sua marca e criam um relacionamento direto com o seu consumidor.<\/b><br \/>\n<span style=\"font-weight: 400\">N\u00e3o desista da estrat\u00e9gia! Se voc\u00ea investir no Marketing de Conte\u00fado, ele tamb\u00e9m ser\u00e1 um grande aliado na resolu\u00e7\u00e3o dos seus problemas com seus canais de redes sociais.<\/span><br \/>\n<i><span style=\"font-weight: 400\">Mas como uma coisa se relaciona a outra?<\/span><\/i><br \/>\n<span style=\"font-weight: 400\">Nas redes sociais os usu\u00e1rios buscam muita coisa: entretenimento, engajamento, conhecimento\u2026 e, \u00e9 claro, resolu\u00e7\u00f5es de d\u00favidas. Al\u00e9m de gerar conte\u00fado para voc\u00ea garantir que n\u00e3o ficar\u00e1 mais sem postagens na sua <\/span><a href=\"https:\/\/rockcontent.com\/blog\/fanpage\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">p\u00e1gina do Facebook<\/span><\/a><span style=\"font-weight: 400\">, por exemplo, o Marketing de Conte\u00fado tamb\u00e9m ajudar\u00e1 sua empresa a ser <\/span><b>mais relevante nas redes sociais,<\/b><span style=\"font-weight: 400\"> j\u00e1 que voc\u00ea estar\u00e1 disponibilizando conte\u00fado gratuito e do interesse do seu p\u00fablico.<\/span><br \/>\n<span style=\"font-weight: 400\">Se o usu\u00e1rio gostar muito do seu blog post ou e-book, ele compartilhar\u00e1 o post com seus amigos, e sua visibilidade ser\u00e1 muito maior. Resumindo: nunca deixe de promover os conte\u00fados do seu blog nas suas redes sociais, hein?<\/span><br \/>\nO famoso Gary Vaynerchuk at\u00e9 escreveu um livro, <a href=\"https:\/\/app.adjust.com\/7mvfth8?deeplink=twelvemin:\/\/book\/nocaute&amp;redirect_windows=https:\/\/12min.com\/br\/nocaute&amp;redirect_macos=https:\/\/12min.com\/br\/nocaute\" target=\"_blank\" rel=\"noopener\">Nocaute<\/a>, com dicas precios\u00edssimas de comportamento em cada rede social.<\/p>\n<p><a class=\"12min-widget\" href=\"https:\/\/12min.com\/nocaute\">Nocaute<\/a><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 4: O Marketing de Conte\u00fado faz a sua marca se tornar uma autoridade na \u00e1rea<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Outro motivo excelente para empresas investirem em Marketing de Conte\u00fado \u00e9 a <\/span><b>autoridade. <\/b><span style=\"font-weight: 400\">Ao produzir sempre conte\u00fados de relev\u00e2ncia e que sanem as d\u00favidas dos seus leitores e potenciais clientes, voc\u00ea estar\u00e1 se colocando como uma autoridade no assunto.<\/span><br \/>\n<span style=\"font-weight: 400\">Vamos supor que sua empresa vende suplementos alimentares, por exemplo. Quando algu\u00e9m tiver d\u00favidas sobre o assunto (como qual suplemento \u00e9 o ideal para ele) voc\u00ea quer que sua empresa seja a primeira que ele vai se lembrar, certo?<\/span><br \/>\n<span style=\"font-weight: 400\">O Marketing de Conte\u00fado vai fazer isso por voc\u00ea! A frequ\u00eancia de produ\u00e7\u00e3o \u00e9 chave para conseguir autoridade. Quando mais conte\u00fado que resolve um problema para seu p\u00fablico voc\u00ea tiver, maiores as chances da sua marca ser vista como uma autoridade absoluta no mercado.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 5: Crescer sua rede de clientes e potenciais clientes<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Esse \u00e9 o motivo mais interessante para empresas investirem na estrat\u00e9gia de Marketing de Conte\u00fado. Como ele ajudar\u00e1 voc\u00ea a conseguir novos clientes?<\/span><br \/>\n<span style=\"font-weight: 400\">Com o Marketing de Conte\u00fado, voc\u00ea conduzir\u00e1 a sua persona por um <\/span><a href=\"https:\/\/rockcontent.com\/blog\/funil-de-vendas\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">funil de vendas<\/span><\/a>,\u00a0<span style=\"font-weight: 400\">produzindo cada vez mais conte\u00fado mais aprofundado para o est\u00e1gio que ela est\u00e1 no funil.<\/span><br \/>\n<span style=\"font-weight: 400\">No topo do funil, por exemplo, \u00e9 quando o usu\u00e1rio encontrar\u00e1 sua empresa no Google. Posts no blog s\u00e3o as maiores armas dessa fase! Nesse momento, o usu\u00e1rio ainda n\u00e3o sabe que tem um problema que precisa ser resolvido. Aqui, o foco \u00e9 <\/span><b>criar conte\u00fado relevante e de atra\u00e7\u00e3o<\/b><span style=\"font-weight: 400\">, para que o seu leitor continue voltando ao seu blog, virando um leitor fiel, para assim ele seguir para as pr\u00f3ximas etapas do funil.<\/span><br \/>\n<span style=\"font-weight: 400\">No meio e no fundo do funil o foco \u00e9 na produ\u00e7\u00e3o de conte\u00fado mais aprofundado e mais focado em resolver as dores do seu agora potencial cliente, at\u00e9 que ele perceba que voc\u00ea est\u00e1 oferecendo uma \u00f3tima solu\u00e7\u00e3o para a necessidade que ele tem! Resumindo, o Marketing de Conte\u00fado \u00e9 uma forma a longo prazo de atrair potenciais clientes fi\u00e9is para a sua marca.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 6: O Marketing de Conte\u00fado cria uma rela\u00e7\u00e3o mais pr\u00f3xima entre marca e leitores\/clientes<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Se um blog sempre fornecer conte\u00fado relevante, interessante e de qualidade para voc\u00ea, qual seria a sua rela\u00e7\u00e3o com ele? Com certeza, esse blog estaria salvo na sua aba de favoritos e voc\u00ea confiaria cegamente nas publica\u00e7\u00f5es que eles fazem.<\/span><br \/>\n<span style=\"font-weight: 400\">O Marketing de Conte\u00fado funciona com esse valor. Voc\u00ea quer, afinal, que os seus leitores e potenciais clientes <\/span><b>confiem em voc\u00ea. <\/b><span style=\"font-weight: 400\">O Marketing de Conte\u00fado bem feito consegue criar uma rela\u00e7\u00e3o muito mais \u00edntima entre marca e leitor, j\u00e1 que os usu\u00e1rios que entram no seu blog (e continuam voltando) est\u00e3o mostrando que aqueles conte\u00fados s\u00e3o relevantes para eles.<\/span><br \/>\n<span style=\"font-weight: 400\">A estrat\u00e9gia consegue te dar dados muito interessantes sobre as dores da sua persona, criando la\u00e7os muito mais pr\u00f3ximos entre a sua empresa e o seu p\u00fablico.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Motivo 7: O Marketing de Conte\u00fado \u00e9 muito mais barato que o Marketing tradicional<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Se os outros 6 motivos que listamos n\u00e3o conseguiram convencer voc\u00ea, com certeza o nosso \u00faltimo motivo far\u00e1 voc\u00ea considerar adotar o Marketing de Conte\u00fado para a sua empresa: a <\/span><b>estrat\u00e9gia \u00e9 muito mais barata (e atrativa) do que o <\/b><a href=\"https:\/\/rockcontent.com\/blog\/publicidade\/\" target=\"_blank\" rel=\"noopener\"><b>Marketing tradicional<\/b><\/a><b>.<\/b><br \/>\n<span style=\"font-weight: 400\">A publicidade tradicional pode n\u00e3o ser a forma mais efetiva de divulgar a sua marca. Ela \u00e9 invasiva, nem sempre \u00e9 segmentada para o p\u00fablico certo (como segmentar um outdoor, por exemplo?) e n\u00e3o pode ser mensurada. N\u00e3o estamos falando para voc\u00ea abandonar a publicidade tradicional (ela pode ser \u00fatil para v\u00e1rias coisas!), mas sim para repensar onde o seu investimento valer\u00e1 mais a pena.<\/span><br \/>\n<span style=\"font-weight: 400\">V\u00ea como o Marketing de Conte\u00fado \u00e9 mais ben\u00e9fico? Claro que demandar\u00e1 tempo e esfor\u00e7o do seu lado, j\u00e1 que o Marketing de Conte\u00fado funciona a longo prazo (e voc\u00ea tamb\u00e9m precisar\u00e1 de dinheiro para contratar profissionais dedicados ao seu blog ou para contratar alguma empresa especialista no assunto).<\/span><br \/>\n<span style=\"font-weight: 400\">Mas mesmo assim, no fim, a estrat\u00e9gia ainda \u00e9 muito mais em conta (e duradoura) do que investir em uma propaganda na televis\u00e3o, por exemplo, que n\u00e3o pode ser <\/span><b>mensurada<\/b><span style=\"font-weight: 400\">, ao contr\u00e1rio do Marketing de Conte\u00fado, onde voc\u00ea consegue medir exatamente todas as m\u00e9tricas essenciais para descobrir se voc\u00ea est\u00e1 tendo ou n\u00e3o bons resultados.<\/span><br \/>\n<span style=\"font-weight: 400\">Esperamos que voc\u00ea tenha tirado as suas d\u00favidas sobre o assunto e que agora esteja pronto para investir na estrat\u00e9gia! <\/span><b>N\u00e3o desista: os resultados no Marketing de Conte\u00fado chegam com o tempo.<\/b><br \/>\n<span style=\"font-weight: 400\">Se voc\u00ea ficou com alguma d\u00favida, n\u00e3o deixe de acessar o nosso blog: <\/span><a href=\"https:\/\/rockcontent.com\/blog\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">rockcontent.com\/blog<\/span><\/a><span style=\"font-weight: 400\">.<\/span><br \/>\nE para se aprofundar no assunto, n\u00e3o perca o\u00a0<a href=\"https:\/\/app.adjust.com\/7mvfth8?deeplink=twelvemin:\/\/book\/marketing-de-conteudo-epico&amp;redirect_windows=https:\/\/12min.com\/br\/marketing-de-conteudo-epico&amp;redirect_macos=https:\/\/12min.com\/br\/marketing-de-conteudo-epico\" target=\"_blank\" rel=\"noopener\">Marketing de Conte\u00fado \u00c9pico<\/a>, livro do\u00a0Joe Pulizzi!<\/p>\n<p><a class=\"12min-widget\" href=\"https:\/\/12min.com\/marketing-de-conteudo-epico\">Marketing de Conte\u00fado \u00c9pico<\/a><br \/>\n________________________________________________________________________________<br \/>\nEsse texto foi escrito pela equipe da <a href=\"https:\/\/rockcontent.com\/\" target=\"_blank\" rel=\"noopener\">Rock Content<\/a>, a maior empresa de Marketing de Conte\u00fado do Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>6 min de leitura \u231a&nbsp;Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Nos \u00faltimos anos, a estrat\u00e9gia vem ganhando cada vez mais reconhecimento e muitas empresas est\u00e3o investindo pesado no uso do conte\u00fado de qualidade para atrair o seu p\u00fablico. Quase 92% das empresas entrevistadas pela pesquisa Content Trends [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-913","post","type-post","status-publish","format-standard","hentry","category-negocios","wpbf-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por que o Marketing de Conte\u00fado \u00e9 importante - 12minutos - Blog<\/title>\n<meta name=\"description\" content=\"Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Mas voc\u00ea sabe por que ele \u00e9 t\u00e3o importante para qualquer neg\u00f3cio?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que o Marketing de Conte\u00fado \u00e9 importante - 12minutos - Blog\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Mas voc\u00ea sabe por que ele \u00e9 t\u00e3o importante para qualquer neg\u00f3cio?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do 12min\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-18T21:33:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-26T18:13:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2017\/09\/marketing-de-conte\u00fado-12-minutos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emir Zecovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emir Zecovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que o Marketing de Conte\u00fado \u00e9 importante - 12minutos - Blog","description":"Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Mas voc\u00ea sabe por que ele \u00e9 t\u00e3o importante para qualquer neg\u00f3cio?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/","og_locale":"en_US","og_type":"article","og_title":"Por que o Marketing de Conte\u00fado \u00e9 importante - 12minutos - Blog","og_description":"Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Mas voc\u00ea sabe por que ele \u00e9 t\u00e3o importante para qualquer neg\u00f3cio?","og_url":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/","og_site_name":"Blog do 12min","article_published_time":"2017-09-18T21:33:02+00:00","article_modified_time":"2018-10-26T18:13:12+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/blog.12min.com\/br\/wp-content\/uploads\/sites\/3\/2017\/09\/marketing-de-conte\u00fado-12-minutos.jpg","type":"image\/jpeg"}],"author":"Emir Zecovic","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Emir Zecovic","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/","url":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/","name":"Por que o Marketing de Conte\u00fado \u00e9 importante - 12minutos - Blog","isPartOf":{"@id":"https:\/\/blog.12min.com\/br\/#website"},"datePublished":"2017-09-18T21:33:02+00:00","dateModified":"2018-10-26T18:13:12+00:00","author":{"@id":"https:\/\/blog.12min.com\/br\/#\/schema\/person\/ccaf1a7ac6cac4265aa3afb02ae667f4"},"description":"Voc\u00ea provavelmente j\u00e1 ouviu ou leu o termo Marketing de Conte\u00fado em algum lugar. Mas voc\u00ea sabe por que ele \u00e9 t\u00e3o importante para qualquer neg\u00f3cio?","breadcrumb":{"@id":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.12min.com\/br\/marketing-de-conteudo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog.12min.com\/br\/"},{"@type":"ListItem","position":2,"name":"Por que o Marketing de Conte\u00fado \u00e9 importante para qualquer neg\u00f3cio"}]},{"@type":"WebSite","@id":"https:\/\/blog.12min.com\/br\/#website","url":"https:\/\/blog.12min.com\/br\/","name":"Blog do 12min","description":"Livros, Audiobooks e Resumos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.12min.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blog.12min.com\/br\/#\/schema\/person\/ccaf1a7ac6cac4265aa3afb02ae667f4","name":"Emir Zecovic","description":"Emir is the Head of Marketing\u00a0at 12min. In his spare time, he loves to meditate and play soccer.","url":"https:\/\/blog.12min.com\/br\/author\/emir\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":4,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"predecessor-version":[{"id":4756,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/posts\/913\/revisions\/4756"}],"wp:attachment":[{"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.12min.com\/br\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}